{"id":7,"count":1,"description":"","link":"https:\/\/birpub.org\/ijlskm\/category\/broder\/","name":"broder","slug":"broder","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v26.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>broder Archives - International Journal of Library Science and Knowledge Management (IJLSKM)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/birpub.org\/ijlskm\/category\/broder\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"broder Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/birpub.org\/ijlskm\/category\/broder\/\" \/>\n<meta property=\"og:site_name\" content=\"International Journal of Library Science and Knowledge Management (IJLSKM)\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/birpub.org\/ijlskm\/category\/broder\/\",\"url\":\"https:\/\/birpub.org\/ijlskm\/category\/broder\/\",\"name\":\"broder Archives - International Journal of Library Science and Knowledge Management (IJLSKM)\",\"isPartOf\":{\"@id\":\"https:\/\/birpub.org\/ijlskm\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/birpub.org\/ijlskm\/category\/broder\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/birpub.org\/ijlskm\/category\/broder\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/birpub.org\/ijlskm\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"broder\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/birpub.org\/ijlskm\/#website\",\"url\":\"https:\/\/birpub.org\/ijlskm\/\",\"name\":\"International Journal of Library Science and Knowledge Management (IJLSKM)\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/birpub.org\/ijlskm\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"broder Archives - International Journal of Library Science and Knowledge Management (IJLSKM)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/birpub.org\/ijlskm\/category\/broder\/","og_locale":"en_US","og_type":"article","og_title":"broder Archives","og_url":"https:\/\/birpub.org\/ijlskm\/category\/broder\/","og_site_name":"International Journal of Library Science and Knowledge Management (IJLSKM)","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/birpub.org\/ijlskm\/category\/broder\/","url":"https:\/\/birpub.org\/ijlskm\/category\/broder\/","name":"broder Archives - International Journal of Library Science and Knowledge Management (IJLSKM)","isPartOf":{"@id":"https:\/\/birpub.org\/ijlskm\/#website"},"breadcrumb":{"@id":"https:\/\/birpub.org\/ijlskm\/category\/broder\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/birpub.org\/ijlskm\/category\/broder\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/birpub.org\/ijlskm\/"},{"@type":"ListItem","position":2,"name":"broder"}]},{"@type":"WebSite","@id":"https:\/\/birpub.org\/ijlskm\/#website","url":"https:\/\/birpub.org\/ijlskm\/","name":"International Journal of Library Science and Knowledge Management (IJLSKM)","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/birpub.org\/ijlskm\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/birpub.org\/ijlskm\/wp-json\/wp\/v2\/categories\/7","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/birpub.org\/ijlskm\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/birpub.org\/ijlskm\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/birpub.org\/ijlskm\/wp-json\/wp\/v2\/posts?categories=7"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}